{"id":15978114,"date":"2026-05-13T19:50:49","date_gmt":"2024-07-02T23:48:26","guid":{"rendered":"https:\/\/myallmeeting.com\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/"},"modified":"2026-05-13T21:50:49","modified_gmt":"2026-05-13T19:50:49","slug":"7952-ibis-styles-paris-cadet-lafayette","status":"publish","type":"hotel","link":"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/","title":{"rendered":"7952 &#8211; ibis Styles Paris Cadet Lafayette"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","service":[586,588,606],"marque":[113],"ville":[8914],"partenaire":[],"type-meeting":[472,526],"periscope_activite_tax":[1670,1667,1684,1680],"periscope_lieu_tax":[1675,1677,1659],"class_list":["post-15978114","hotel","type-hotel","status-publish","hentry","service-chambres-communicantes","service-connexion-internet-sans-fil-dans-les-espaces-publics","service-services-internet","marque-ibs","ville-paris","type-meeting-hebergement-groupe","type-meeting-soiree-evenements","periscope_activite_tax-culture-art-creation","periscope_activite_tax-gastronomie","periscope_activite_tax-jeux-en-equipe","periscope_activite_tax-decouverte-patrimoine","periscope_lieu_tax-capitale","periscope_lieu_tax-historique","periscope_lieu_tax-urbain"],"acf":[],"yoast_head":"<title>7952 - ibis Styles Paris Cadet Lafayette - Accor MyAllMeeting.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/hotel\/15978114\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7952 - ibis Styles Paris Cadet Lafayette - Accor MyAllMeeting.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/\" \/>\n<meta property=\"og:site_name\" content=\"Accor MyAllMeeting.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T19:50:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/\",\"url\":\"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/\",\"name\":\"7952 - ibis Styles Paris Cadet Lafayette - Accor MyAllMeeting.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.myallmeeting.com\/pl\/#website\"},\"datePublished\":\"2024-07-02T23:48:26+00:00\",\"dateModified\":\"2026-05-13T19:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/myallmeeting.com\/pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel\",\"item\":\"https:\/\/myallmeeting.com\/pl\/hotel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"7952 &#8211; ibis Styles Paris Cadet Lafayette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.myallmeeting.com\/pl\/#website\",\"url\":\"https:\/\/www.myallmeeting.com\/pl\/\",\"name\":\"Accor MyAllMeeting.com\",\"description\":\"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels\",\"publisher\":{\"@id\":\"https:\/\/www.myallmeeting.com\/pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.myallmeeting.com\/pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.myallmeeting.com\/pl\/#organization\",\"name\":\"ACCOR\",\"url\":\"https:\/\/www.myallmeeting.com\/pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/www.myallmeeting.com\/pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ACCOR\"},\"image\":{\"@id\":\"https:\/\/www.myallmeeting.com\/pl\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"7952 - ibis Styles Paris Cadet Lafayette - Accor MyAllMeeting.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/hotel\/15978114","og_locale":"pl_PL","og_type":"article","og_title":"7952 - ibis Styles Paris Cadet Lafayette - Accor MyAllMeeting.com","og_url":"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/","og_site_name":"Accor MyAllMeeting.com","article_modified_time":"2026-05-13T19:50:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/","url":"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/","name":"7952 - ibis Styles Paris Cadet Lafayette - Accor MyAllMeeting.com","isPartOf":{"@id":"https:\/\/www.myallmeeting.com\/pl\/#website"},"datePublished":"2024-07-02T23:48:26+00:00","dateModified":"2026-05-13T19:50:49+00:00","breadcrumb":{"@id":"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/myallmeeting.com\/pl\/hotel\/7952-ibis-styles-paris-cadet-lafayette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/myallmeeting.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Hotel","item":"https:\/\/myallmeeting.com\/pl\/hotel\/"},{"@type":"ListItem","position":3,"name":"7952 &#8211; ibis Styles Paris Cadet Lafayette"}]},{"@type":"WebSite","@id":"https:\/\/www.myallmeeting.com\/pl\/#website","url":"https:\/\/www.myallmeeting.com\/pl\/","name":"Accor MyAllMeeting.com","description":"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels","publisher":{"@id":"https:\/\/www.myallmeeting.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myallmeeting.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.myallmeeting.com\/pl\/#organization","name":"ACCOR","url":"https:\/\/www.myallmeeting.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.myallmeeting.com\/pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ACCOR"},"image":{"@id":"https:\/\/www.myallmeeting.com\/pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/hotel\/15978114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/types\/hotel"}],"wp:attachment":[{"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/media?parent=15978114"}],"wp:term":[{"taxonomy":"service","embeddable":true,"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/service?post=15978114"},{"taxonomy":"marque","embeddable":true,"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/marque?post=15978114"},{"taxonomy":"ville","embeddable":true,"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/ville?post=15978114"},{"taxonomy":"partenaire","embeddable":true,"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/partenaire?post=15978114"},{"taxonomy":"type-meeting","embeddable":true,"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/type-meeting?post=15978114"},{"taxonomy":"periscope_activite_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/periscope_activite_tax?post=15978114"},{"taxonomy":"periscope_lieu_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/pl\/wp-json\/wp\/v2\/periscope_lieu_tax?post=15978114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}