{"id":16552633,"date":"2024-10-30T10:21:45","date_gmt":"2024-10-30T09:21:45","guid":{"rendered":"https:\/\/myallmeeting.com\/?post_type=article&#038;p=16552633"},"modified":"2025-07-29T15:52:33","modified_gmt":"2025-07-29T13:52:33","slug":"saintclair","status":"publish","type":"article","link":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/","title":{"rendered":"SAINTCLAIR"},"content":{"rendered":"<!-- START OF : Composant : block-periscope-theme-section-composant-25-texte-cta-2-images.php -->\n<div class=\"tcta2ia bg-white fs-wysiwyg mb-lg-12\" data-component=\"25-texte-cta-2-images\">\n\t<div class=\"tcta2ia__top\">\n\t\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t\t<div class=\"col-lg-8\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"bloc-mise-en-avant__top__left\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-23.png\" class=\"pe-2 pe-lg-0\" width=\"1268\" height=\"846\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"tcta2ia__bottom d-none d-lg-block pb-12 pt-lg-9 pb-lg-0 pe-lg-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-32 fw-semibold\">L\u2019audace, signature des Exp\u00e9riences SAINTCLAIR.<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fs-wysiwyg\"><p>Elle fait partie int\u00e9grante de notre ADN : une audace cr\u00e9ative et ma\u00eetris\u00e9e, qui infuse chacune de nos r\u00e9alisations. L\u2019objectif ? Vous offrir plus qu\u2019un \u00e9v\u00e8nement, en vous emportant au coeur d\u2019une rencontre exp\u00e9rientielle inoubliable.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"d-flex flex-column flex-lg-row align-items-center gap-5 gap-lg-8 justify-content-between\">\n\t\t\t\t\t\t\t<div class=\"fs-20 fs-lg-26 fw-semibold lh-xs\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-lg-4\">\n\t\t\t\t\t<div class=\"tcta2ia__top__right t-0 r-0 bg-primary text-white pt-4 pb-4 px-2 pt-lg-8 pb-lg-16 px-lg-11 pb-xl-30\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"unna fs-36 fs-lg-51 fs-xl-75 fs-italic fw-normal text-secondary\">SAINTCLAIR<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"text-white fs-18 fs-lg-20 fs-xl-28 text-original-case\">Le go\u00fbt de la rencontre.<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fs-wysiwyg mb-4 fs-lg-16 fs-xl-20\"><p>Fa\u00e7onner une exp\u00e9rience d\u2019exception, o\u00f9 s\u2019expriment l\u2019audace et la modernit\u00e9 pourbousculer les codes.<br \/>\nVivre ensemble une odyss\u00e9e sensorielle intense, o\u00f9 haute gastronomie et mise en sc\u00e8ne cr\u00e9ative donnent vie \u00e0 une rencontre humaine et singuli\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Pour toute information suppl\u00e9mentaire ou r\u00e9servation, veuillez contacter <strong><a aria-label=\"Link Louise.GABILLAUD@accor.com\" id=\"menurbg8\" href=\"mailto:Louise.GABILLAUD@accor.com\" rel=\"noreferrer noopener\" target=\"_blank\" class=\"fui-Link ___1q1shib f2hkw1w f3rmtva f1ewtqcl fyind8e f1k6fduh f1w7gpdv fk6fouc fjoy568 figsok6 f1s184ao f1mk8lai fnbmjn9 f1o700av f13mvf36 f1cmlufx f9n3di6 f1ids18y f1tx3yz7 f1deo86v f1eh06m1 f1iescvh fhgqx19 f1olyrje f1p93eir f1nev41a f1h8hb77 f1lqvz6u f10aw75t fsle3fq f17ae5zn\" title=\"mailto:louise.gabillaud@accor.com\">Louise.GABILLAUD@accor.com<\/a><\/strong><\/em><!--more--><\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"m-0\"><img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-25-633x398.png\" class=\"position-relative l-0\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/><\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"tcta2ia__bottom d-lg-none pb-12 py-lg-9 pe-lg-10\">\n\t\t\t\t<div class=\"h2 fs-20 fs-lg-32 fw-semibold\">L\u2019audace, signature des Exp\u00e9riences SAINTCLAIR.<\/div>\n\t\t\t\t\t\t<div class=\"fs-wysiwyg\"><p>Elle fait partie int\u00e9grante de notre ADN : une audace cr\u00e9ative et ma\u00eetris\u00e9e, qui infuse chacune de nos r\u00e9alisations. L\u2019objectif ? Vous offrir plus qu\u2019un \u00e9v\u00e8nement, en vous emportant au coeur d\u2019une rencontre exp\u00e9rientielle inoubliable.<\/p>\n<\/div>\n\t\t\t\t<div class=\"d-flex flex-column flex-lg-row align-items-center gap-5 gap-lg-8 justify-content-between\">\n\t\t\t<div class=\"fs-20 fs-lg-26 fw-semibold lh-xs\"><\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<!-- END OF : Composant : block-periscope-theme-section-composant-25-texte-cta-2-images.php -->\n\n\n<!-- START OF : Composant : block-periscope-theme-section-composant-33-texte-image.php -->\n<!-- INVERSE -->\n<div class=\"text-image fs-wysiwyg mb-8 mb-lg-12\" data-component=\"33-texte-image\" data-reverse=\"oui\">\n\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t<div class=\"text-image__content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"fw-semibold lh-xs fs-20 fs-lg-32 ls--25 mb-5\">Penser la cr\u00e9ation autrement. Voir les choses sous un nouveau prisme. D\u00e9passer les conventions tout en gardant la ma\u00eetrise.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fs-wysiwyg\">\n\t\t\t\t\t\t<p>C\u2019est ainsi que nous envisageons chacune de nos rencontres : gr\u00e2ce \u00e0 plus de 40 ann\u00e9es d\u2019exp\u00e9rience et au talent de nos \u00e9quipes, nous sommes en mesure de vous proposer une exp\u00e9rience diff\u00e9rente et surprenante sans que rien ne nous \u00e9chappe jamais.<br \/>\nEn cocktail d\u00eenatoire ou en repas assis, lors d\u2019un gala ou d\u2019une rencontre intimiste : quel que soit l\u2019\u00e9v\u00e8nement et son ampleur, nous mettons notre cr\u00e9ativit\u00e9 et notre go\u00fbt pour l\u2019avant-garde \u00e0 profit pour le fa\u00e7onner en un moment unique.<br \/>\nDe la gastronomie \u00e0 la sc\u00e9nographie, en passant par les animations ou le service : d\u00e9couvrez comment tout un univers peut envelopper chaque instant d\u2019une rencontre et en faire une exp\u00e9rience immersive et sensorielle m\u00e9morable.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>    \n\t\t\t    \n\t\t\t<div class=\"col-lg-6 order-first order-lg-last mb-7 mb-lg-0\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-24.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" class=\"w-100\" \/>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<!-- END OF : Composant : block-periscope-theme-section-composant-33-texte-image.php -->\n\n\n<!-- START OF : Composant : block-periscope-theme-section-composant-26-textes-slider-cta.php -->\n<div class=\"t3icta bg-white pb-12 mb-9 fs-wysiwyg\" data-component=\"26-textes-3-images-cta\">\n\t<div class=\"t3icta__top position-relative\">\n\t\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t<div class=\"t3icta__slider\">\n\t\t\t\t\t\t<div class=\"splide\">\n\t\t\t\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-8.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-26.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-13.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-27.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-28.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"splide__arrows d-none d-lg-block\">\n\t\t\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--prev px-lg-3 py-lg-4 px-xl-4 py-xl-5 px-xxl-5 py-xxl-7 position-absolute l-0 bg-white border-0\">\n\t\t\t\t\t\t\t\t\t<svg width=\"14\" height=\"27\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t<use xlink:href=\"https:\/\/myallmeeting.com\/wp-content\/themes\/accor\/assets\/images\/sprite.svg#slider-prev\"><\/use>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--next px-lg-3 py-lg-4 px-xl-4 py-xl-5 px-xxl-5 py-xxl-7 position-absolute r-0 bg-white border-0\">\n\t\t\t\t\t\t\t\t\t<svg width=\"14\" height=\"27\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t<use xlink:href=\"https:\/\/myallmeeting.com\/wp-content\/themes\/accor\/assets\/images\/sprite.svg#slider-prev\"><\/use>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t<div class=\"t3icta__top_right mb-lg-14 px-2 py-9 px-lg-11 py-lg-0\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">Pavillon Dauphine<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"fs-wysiwyg\">\n\t\t\t\t\t\t\t<p>En 2015, ses cl\u00e9s nous sont confi\u00e9es en exclusivit\u00e9 : le Pavillon Dauphine, \u00e9crin d\u2019Histoire et de verdure, devient ainsi un lieu \u00e0 nous\u2026 pour vous.<br \/>\nAvec son architecture unique, ses 900m\u00b2 d\u2019espaces int\u00e9rieurs modulables et ses 3 000m\u00b2 d\u2019espaces ext\u00e9rieurs verdoyants, le Pavillon Dauphine SAINTCLAIR accueille tous vos \u00e9v\u00e9nements, des plus intimes aux plus audacieux. Un lieu \u00e9v\u00e9nementiel parisien unique, dont nous connaissons chaque centim\u00e8tre carr\u00e9, pour mieux mettre ses richesses au service de vos r\u00e9ceptions<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"t3icta__bottom bg-beige\">\n\t\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t\t<div class=\"col-lg-5 offset-lg-1\">\n\t\t\t\t\t<div class=\"t3icta__bottom__left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-12-633x398.png\" class=\"w-100 d-lg-none\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 0 -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-2 py-9 px-lg-0 py-lg-0\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">Une situation privil\u00e9gi\u00e9e, en plein coeur de Paris<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"fs-wysiwyg mb-lg-15\">\n\t\t\t\t\t\t\t\t<p>Situ\u00e9 \u00e0 l\u2019or\u00e9e du Bois de Boulogne et au pied de l\u2019Avenue Foch, le Pavillon Dauphine SAINTCLAIR b\u00e9n\u00e9ficie d\u2019un emplacement d\u2019exception pour vos \u00e9v\u00e9nements priv\u00e9s ou professionnels, de 50 \u00e0 1 500 convives.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t3icta__bottom__img1 d-none d-lg-block text-end ms-lg-auto\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-12-633x398.png\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 1 -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-lg-5\">\n\t\t\t\t\t<div class=\"ps-lg-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-29-633x398.png\" class=\"t3icta__bottom__img0 position-relative d-none d-lg-block mb-15\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 0 -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-2 px-lg-0 mb-9\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">Un cadre intime ou professionnel<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fs-wysiwyg\">\n\t\t\t\t\t\t\t\t<p>Un format confidentiel ou une rencontre d\u2019envergure, une r\u00e9ception en ext\u00e9rieur ou un d\u00eener en int\u00e9rieur : quel que soit votre projet et quelles que soient vos envies, le Pavillon Dauphine accueille tous vos \u00e9v\u00e9nements, pour toutes les occasions, \u00e0 toutes les saisons.<br \/>\nEt pour imaginer et vous accompagner dans votre projet, faites confiance aux \u00e9quipes du Pavillon Dauphine : event planner, sc\u00e9nographes, responsables logistiques, etc.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t3icta__bottom__img1 d-lg-none mx-auto\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-29-633x398.png\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 1 -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<!-- END OF : Composant : block-periscope-theme-section-composant-26-textes-slider-cta.php -->\n\n\n<!-- START OF : Composant : block-periscope-theme-section-composant-26-textes-slider-cta.php -->\n<div class=\"t3icta bg-white pb-12 mb-9 fs-wysiwyg\" data-component=\"26-textes-3-images-cta\">\n\t<div class=\"t3icta__top position-relative\">\n\t\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t<div class=\"t3icta__slider\">\n\t\t\t\t\t\t<div class=\"splide\">\n\t\t\t\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-18.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"splide__arrows d-none d-lg-block\">\n\t\t\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--prev px-lg-3 py-lg-4 px-xl-4 py-xl-5 px-xxl-5 py-xxl-7 position-absolute l-0 bg-white border-0\">\n\t\t\t\t\t\t\t\t\t<svg width=\"14\" height=\"27\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t<use xlink:href=\"https:\/\/myallmeeting.com\/wp-content\/themes\/accor\/assets\/images\/sprite.svg#slider-prev\"><\/use>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--next px-lg-3 py-lg-4 px-xl-4 py-xl-5 px-xxl-5 py-xxl-7 position-absolute r-0 bg-white border-0\">\n\t\t\t\t\t\t\t\t\t<svg width=\"14\" height=\"27\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t<use xlink:href=\"https:\/\/myallmeeting.com\/wp-content\/themes\/accor\/assets\/images\/sprite.svg#slider-prev\"><\/use>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t<div class=\"t3icta__top_right mb-lg-14 px-2 py-9 px-lg-11 py-lg-0\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">24 Place des Vosges<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"fs-wysiwyg\">\n\t\t\t\t\t\t\t<p>Nich\u00e9e au coeur d\u2019un h\u00f4tel particulier du XVII\u00e8me si\u00e8cle dans le Marais historique, cette demeure de caract\u00e8re abrite une magnifique collection d\u2019oeuvres d\u2019art. Repens\u00e9 par l\u2019architecte argentin Patricio Elliff, cet appartement de r\u00e9ception atypique se compose de 2 salons attenants de 110 et 60m\u00b2. Ce cadre d\u2019exception en fait le th\u00e9\u00e2tre id\u00e9al de vos r\u00e9ceptions VIP en petit comit\u00e9 : d\u00eener d\u2019affaires, comit\u00e9 de direction, lancement presse\u2026<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"t3icta__bottom bg-beige\">\n\t\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t\t<div class=\"col-lg-5 offset-lg-1\">\n\t\t\t\t\t<div class=\"t3icta__bottom__left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-19-633x398.png\" class=\"w-100 d-lg-none\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 0 -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-2 py-9 px-lg-0 py-lg-0\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">Un d\u00e9cor de prestige :<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"fs-wysiwyg mb-lg-15\">\n\t\t\t\t\t\t\t\t<p>Une collection d\u2019art singuli\u00e8re o\u00f9 se m\u00ealent avec \u00e9l\u00e9gance et raffinement des oeuvres historiques du XVII\u00e8me si\u00e8cle et de l\u2019art primitif, \u00e0 un mobilier des ann\u00e9es 50 sublim\u00e9 par des mati\u00e8res nobles.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t3icta__bottom__img1 d-none d-lg-block text-end ms-lg-auto\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-19-633x398.png\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 1 -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-lg-5\">\n\t\t\t\t\t<div class=\"ps-lg-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-17-633x398.png\" class=\"t3icta__bottom__img0 position-relative d-none d-lg-block mb-15\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 0 -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-2 px-lg-0 mb-9\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">Un espace compl\u00e9mentaire : Le serpent \u00e0 Plume<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fs-wysiwyg\">\n\t\t\t\t\t\t\t\t<p>Une seule adresse, deux lieux uniques pour votre \u00e9v\u00e8nement. En compl\u00e9ment des espaces du 24, accueillez vos invit\u00e9s pour l\u2019ap\u00e9ritif au sein du Serpent \u00e0 Plume. Bar concept store le jour et espace privatisable le soir, situ\u00e9 au rez-de-chauss\u00e9e du 24 Place des Vosges.<br \/>\nUne fois la boutique travers\u00e9e, empruntez l\u2019escalier qui vous m\u00e8nera dans l\u2019\u00e2me du Serpent \u00e0 Plume. Au sous-sol, sous les vo\u00fbtes en pierre, une cave originale, am\u00e9nag\u00e9e et d\u00e9cor\u00e9e par Vincent Dar\u00e9 pour d\u00e9marrer votre soir\u00e9e en toute confiance.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t3icta__bottom__img1 d-lg-none mx-auto\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-17-633x398.png\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 1 -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<!-- END OF : Composant : block-periscope-theme-section-composant-26-textes-slider-cta.php -->\n\n\n<!-- START OF : Composant : block-periscope-theme-section-composant-26-textes-slider-cta.php -->\n<div class=\"t3icta bg-white pb-12 mb-9 fs-wysiwyg\" data-component=\"26-textes-3-images-cta\">\n\t<div class=\"t3icta__top position-relative\">\n\t\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t<div class=\"t3icta__slider\">\n\t\t\t\t\t\t<div class=\"splide\">\n\t\t\t\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"splide__slide\">\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-20.png\" width=\"953\" height=\"600\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"splide__arrows d-none d-lg-block\">\n\t\t\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--prev px-lg-3 py-lg-4 px-xl-4 py-xl-5 px-xxl-5 py-xxl-7 position-absolute l-0 bg-white border-0\">\n\t\t\t\t\t\t\t\t\t<svg width=\"14\" height=\"27\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t<use xlink:href=\"https:\/\/myallmeeting.com\/wp-content\/themes\/accor\/assets\/images\/sprite.svg#slider-prev\"><\/use>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t<button class=\"splide__arrow splide__arrow--next px-lg-3 py-lg-4 px-xl-4 py-xl-5 px-xxl-5 py-xxl-7 position-absolute r-0 bg-white border-0\">\n\t\t\t\t\t\t\t\t\t<svg width=\"14\" height=\"27\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t<use xlink:href=\"https:\/\/myallmeeting.com\/wp-content\/themes\/accor\/assets\/images\/sprite.svg#slider-prev\"><\/use>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t\t<div class=\"t3icta__top_right mb-lg-14 px-2 py-9 px-lg-11 py-lg-0\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">Cour des Alchimistes<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"fs-wysiwyg\">\n\t\t\t\t\t\t\t<p>Au coeur de l\u2019\u00eele Saint-Louis, la Cour des Alchimistes est un lieu unique, inimitable et inspirant situ\u00e9 dans un immeuble fond\u00e9 en 1609 dont la fa\u00e7ade est class\u00e9e Monument historique.<\/p>\n<p>Ce lieu atypique \u00e9tait jadis fr\u00e9quent\u00e9 par les alchimistes qui s\u2019y retrouvaient pr\u00e8s du puits, dans la cour maintenant couverte, d\u2019o\u00f9 son nom.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"t3icta__bottom bg-beige\">\n\t\t<div class=\"container-fluid\" style=\"--bs-gutter-x: 0\">\n\t\t\t<div class=\"row\" style=\"--bs-gutter-x: 0\">\n\t\t\t\t<div class=\"col-lg-5 offset-lg-1\">\n\t\t\t\t\t<div class=\"t3icta__bottom__left\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-21-633x398.png\" class=\"w-100 d-lg-none\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 0 -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-2 py-9 px-lg-0 py-lg-0\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">La Cour des Alchimistes \u00e9voque le travail Alchimique de Transmutation<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"fs-wysiwyg mb-lg-15\">\n\t\t\t\t\t\t\t\t<p>Ses murs compos\u00e9s d\u2019imposantes pierres d\u2019\u00e9poque et ses plafonds aux poutres de 400 ans respirent l\u2019authenticit\u00e9. C\u2019est un lieu tr\u00e8s min\u00e9ral, dont les \u00e9l\u00e9ments tels que le verre, le m\u00e9tal et les pierres, cr\u00e9ent un pont entre le pass\u00e9 et le futur, le temps y \u00e9tant repr\u00e9sent\u00e9 par des horloges.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t3icta__bottom__img1 d-none d-lg-block text-end ms-lg-auto\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-21-633x398.png\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 1 -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-lg-5\">\n\t\t\t\t\t<div class=\"ps-lg-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-22-633x398.png\" class=\"t3icta__bottom__img0 position-relative d-none d-lg-block mb-15\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 0 -->\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"px-2 px-lg-0 mb-9\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h2 class=\"fs-20 fs-lg-23 fs-xl-27 fs-xxl-30 fw-semibold\">Une d\u00e9coration sur mesure<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fs-wysiwyg\">\n\t\t\t\t\t\t\t\t<p>La d\u00e9coration de la Cour des Alchimistes a \u00e9t\u00e9 con\u00e7ue et r\u00e9alis\u00e9e uniquement par des entreprises labellis\u00e9es Meilleurs Ouvriers de France comme Patrick Forfait pour les vitraux, R\u00e9gis Bertin (artiste-m\u00e9tal) pour les meubles, ou Sylvie Pourel artiste-peintre de l\u2019Ecole de Versailles pour les d\u00e9cors peints\u2026<br \/>\nSon calme proche d\u2019un clo\u00eetre de monast\u00e8re, et son design int\u00e9rieur rappelant le raffinement du baroque fran\u00e7ais, en font le lieu id\u00e9al pour se ressourcer et se d\u00e9charger du stress.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"t3icta__bottom__img1 d-lg-none mx-auto\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-slider-952x600-22-633x398.png\" width=\"633\" height=\"398\" alt=\"\" loading=\"lazy\" \/> <!-- Ce sont les 2 m\u00eames images : ID 1 -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<!-- END OF : Composant : block-periscope-theme-section-composant-26-textes-slider-cta.php -->\n","protected":false},"excerpt":{"rendered":"<p>Le go\u00fbt de la rencontre.<\/p>\n","protected":false},"featured_media":16552752,"menu_order":0,"template":"","periscope_categorie_tax":[],"class_list":["post-16552633","article","type-article","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<title>SAINTCLAIR - Accor MyAllMeeting.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/article\/16552633\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAINTCLAIR - Accor MyAllMeeting.com\" \/>\n<meta property=\"og:description\" content=\"Le go\u00fbt de la rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/\" \/>\n<meta property=\"og:site_name\" content=\"Accor MyAllMeeting.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T13:52:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/\",\"url\":\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/\",\"name\":\"SAINTCLAIR - Accor MyAllMeeting.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.myallmeeting.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png\",\"datePublished\":\"2024-10-30T09:21:45+00:00\",\"dateModified\":\"2025-07-29T13:52:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#primaryimage\",\"url\":\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png\",\"contentUrl\":\"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png\",\"width\":1920,\"height\":570},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/myallmeeting.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\/\/myallmeeting.com\/fr\/actualite\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SAINTCLAIR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.myallmeeting.com\/fr\/#website\",\"url\":\"https:\/\/www.myallmeeting.com\/fr\/\",\"name\":\"Accor MyAllMeeting.com\",\"description\":\"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels\",\"publisher\":{\"@id\":\"https:\/\/www.myallmeeting.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.myallmeeting.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.myallmeeting.com\/fr\/#organization\",\"name\":\"ACCOR\",\"url\":\"https:\/\/www.myallmeeting.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.myallmeeting.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ACCOR\"},\"image\":{\"@id\":\"https:\/\/www.myallmeeting.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"SAINTCLAIR - Accor MyAllMeeting.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/article\/16552633","og_locale":"fr_FR","og_type":"article","og_title":"SAINTCLAIR - Accor MyAllMeeting.com","og_description":"Le go\u00fbt de la rencontre.","og_url":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/","og_site_name":"Accor MyAllMeeting.com","article_modified_time":"2025-07-29T13:52:33+00:00","og_image":[{"width":1920,"height":570,"url":"http:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/","url":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/","name":"SAINTCLAIR - Accor MyAllMeeting.com","isPartOf":{"@id":"https:\/\/www.myallmeeting.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#primaryimage"},"image":{"@id":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#primaryimage"},"thumbnailUrl":"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png","datePublished":"2024-10-30T09:21:45+00:00","dateModified":"2025-07-29T13:52:33+00:00","breadcrumb":{"@id":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myallmeeting.com\/fr\/article\/saintclair\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#primaryimage","url":"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png","contentUrl":"https:\/\/myallmeeting.com\/wp-content\/uploads\/2024\/10\/MAM-imagery-1920-x-570-px-Baniere-15.png","width":1920,"height":570},{"@type":"BreadcrumbList","@id":"https:\/\/myallmeeting.com\/fr\/article\/saintclair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/myallmeeting.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/myallmeeting.com\/fr\/actualite\/"},{"@type":"ListItem","position":3,"name":"SAINTCLAIR"}]},{"@type":"WebSite","@id":"https:\/\/www.myallmeeting.com\/fr\/#website","url":"https:\/\/www.myallmeeting.com\/fr\/","name":"Accor MyAllMeeting.com","description":"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels","publisher":{"@id":"https:\/\/www.myallmeeting.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myallmeeting.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.myallmeeting.com\/fr\/#organization","name":"ACCOR","url":"https:\/\/www.myallmeeting.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.myallmeeting.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ACCOR"},"image":{"@id":"https:\/\/www.myallmeeting.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/article\/16552633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/media\/16552752"}],"wp:attachment":[{"href":"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/media?parent=16552633"}],"wp:term":[{"taxonomy":"periscope_categorie_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/fr\/wp-json\/wp\/v2\/periscope_categorie_tax?post=16552633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}