{"id":17992896,"date":"2026-05-13T14:07:10","date_gmt":"2025-01-22T09:50:14","guid":{"rendered":"https:\/\/myallmeeting.com\/?post_type=hotel&#038;p=17992896"},"modified":"2026-05-13T16:07:10","modified_gmt":"2026-05-13T14:07:10","slug":"1798","status":"publish","type":"hotel","link":"https:\/\/myallmeeting.com\/es\/hotel\/1798\/","title":{"rendered":"1798 &#8211; Novotel Firenze Nord Aeroporto"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","service":[591,586,603,587,588,590,596,595,601,606],"marque":[25],"ville":[9668],"partenaire":[],"type-meeting":[],"periscope_activite_tax":[],"periscope_lieu_tax":[],"class_list":["post-17992896","hotel","type-hotel","status-publish","hentry","service-groom","service-chambres-communicantes","service-safe-deposit-box","service-concierge-desk","service-connexion-internet-sans-fil-dans-les-espaces-publics","service-equipement-audio-visuel","service-parking-pour-bus","service-outdoor-pool","service-reception-ouverte-24h-24","service-services-internet","marque-nov","ville-firenze"],"acf":[],"yoast_head":"<title>1798 - Novotel Firenze Nord Aeroporto - Accor MyAllMeeting.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/hotel\/17992896\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1798 - Novotel Firenze Nord Aeroporto - Accor MyAllMeeting.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myallmeeting.com\/es\/hotel\/1798\/\" \/>\n<meta property=\"og:site_name\" content=\"Accor MyAllMeeting.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:07:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myallmeeting.com\/es\/hotel\/1798\/\",\"url\":\"https:\/\/myallmeeting.com\/es\/hotel\/1798\/\",\"name\":\"1798 - Novotel Firenze Nord Aeroporto - Accor MyAllMeeting.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.myallmeeting.com\/es\/#website\"},\"datePublished\":\"2025-01-22T09:50:14+00:00\",\"dateModified\":\"2026-05-13T14:07:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myallmeeting.com\/es\/hotel\/1798\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myallmeeting.com\/es\/hotel\/1798\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myallmeeting.com\/es\/hotel\/1798\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina principal\",\"item\":\"https:\/\/myallmeeting.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel\",\"item\":\"https:\/\/myallmeeting.com\/es\/hotel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1798 &#8211; Novotel Firenze Nord Aeroporto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.myallmeeting.com\/es\/#website\",\"url\":\"https:\/\/www.myallmeeting.com\/es\/\",\"name\":\"Accor MyAllMeeting.com\",\"description\":\"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels\",\"publisher\":{\"@id\":\"https:\/\/www.myallmeeting.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.myallmeeting.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.myallmeeting.com\/es\/#organization\",\"name\":\"ACCOR\",\"url\":\"https:\/\/www.myallmeeting.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.myallmeeting.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ACCOR\"},\"image\":{\"@id\":\"https:\/\/www.myallmeeting.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"1798 - Novotel Firenze Nord Aeroporto - Accor MyAllMeeting.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/hotel\/17992896","og_locale":"es_ES","og_type":"article","og_title":"1798 - Novotel Firenze Nord Aeroporto - Accor MyAllMeeting.com","og_url":"https:\/\/myallmeeting.com\/es\/hotel\/1798\/","og_site_name":"Accor MyAllMeeting.com","article_modified_time":"2026-05-13T14:07:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myallmeeting.com\/es\/hotel\/1798\/","url":"https:\/\/myallmeeting.com\/es\/hotel\/1798\/","name":"1798 - Novotel Firenze Nord Aeroporto - Accor MyAllMeeting.com","isPartOf":{"@id":"https:\/\/www.myallmeeting.com\/es\/#website"},"datePublished":"2025-01-22T09:50:14+00:00","dateModified":"2026-05-13T14:07:10+00:00","breadcrumb":{"@id":"https:\/\/myallmeeting.com\/es\/hotel\/1798\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myallmeeting.com\/es\/hotel\/1798\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/myallmeeting.com\/es\/hotel\/1798\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina principal","item":"https:\/\/myallmeeting.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hotel","item":"https:\/\/myallmeeting.com\/es\/hotel\/"},{"@type":"ListItem","position":3,"name":"1798 &#8211; Novotel Firenze Nord Aeroporto"}]},{"@type":"WebSite","@id":"https:\/\/www.myallmeeting.com\/es\/#website","url":"https:\/\/www.myallmeeting.com\/es\/","name":"Accor MyAllMeeting.com","description":"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels","publisher":{"@id":"https:\/\/www.myallmeeting.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myallmeeting.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.myallmeeting.com\/es\/#organization","name":"ACCOR","url":"https:\/\/www.myallmeeting.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.myallmeeting.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ACCOR"},"image":{"@id":"https:\/\/www.myallmeeting.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/hotel\/17992896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/types\/hotel"}],"wp:attachment":[{"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/media?parent=17992896"}],"wp:term":[{"taxonomy":"service","embeddable":true,"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/service?post=17992896"},{"taxonomy":"marque","embeddable":true,"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/marque?post=17992896"},{"taxonomy":"ville","embeddable":true,"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/ville?post=17992896"},{"taxonomy":"partenaire","embeddable":true,"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/partenaire?post=17992896"},{"taxonomy":"type-meeting","embeddable":true,"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/type-meeting?post=17992896"},{"taxonomy":"periscope_activite_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/periscope_activite_tax?post=17992896"},{"taxonomy":"periscope_lieu_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/es\/wp-json\/wp\/v2\/periscope_lieu_tax?post=17992896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}