{"id":59913,"date":"2026-05-13T04:51:48","date_gmt":"2020-10-13T10:51:13","guid":{"rendered":"https:\/\/myallmeeting.com\/hotel\/5944-ibis-barcelona-pza-glories-22\/"},"modified":"2026-05-13T06:51:48","modified_gmt":"2026-05-13T04:51:48","slug":"5944-ibis-barcelona-pza-glories-22","status":"publish","type":"hotel","link":"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/","title":{"rendered":"5944 &#8211; ibis Barcelona Plaza Glories 22"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","service":[586,603,588,593,601,606],"marque":[1600],"ville":[9409],"partenaire":[],"type-meeting":[472],"periscope_activite_tax":[],"periscope_lieu_tax":[],"class_list":["post-59913","hotel","type-hotel","status-publish","hentry","service-chambres-communicantes","service-safe-deposit-box","service-connexion-internet-sans-fil-dans-les-espaces-publics","service-multilingual-staff","service-reception-ouverte-24h-24","service-services-internet","marque-ibh","ville-barcelone","type-meeting-hebergement-groupe"],"acf":[],"yoast_head":"<title>5944 - ibis Barcelona Plaza Glories 22 - Accor MyAllMeeting.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel\/59913\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5944 - ibis Barcelona Plaza Glories 22 - Accor MyAllMeeting.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/\" \/>\n<meta property=\"og:site_name\" content=\"Accor MyAllMeeting.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T04:51:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/\",\"url\":\"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/\",\"name\":\"5944 - ibis Barcelona Plaza Glories 22 - Accor MyAllMeeting.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#website\"},\"datePublished\":\"2020-10-13T10:51:13+00:00\",\"dateModified\":\"2026-05-13T04:51:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/myallmeeting.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel\",\"item\":\"https:\/\/myallmeeting.com\/en\/hotel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5944 &#8211; ibis Barcelona Plaza Glories 22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#website\",\"url\":\"https:\/\/www.myallmeeting.com\/en\/\",\"name\":\"Accor MyAllMeeting.com\",\"description\":\"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels\",\"publisher\":{\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.myallmeeting.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#organization\",\"name\":\"ACCOR\",\"url\":\"https:\/\/www.myallmeeting.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ACCOR\"},\"image\":{\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"5944 - ibis Barcelona Plaza Glories 22 - Accor MyAllMeeting.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel\/59913","og_locale":"en_US","og_type":"article","og_title":"5944 - ibis Barcelona Plaza Glories 22 - Accor MyAllMeeting.com","og_url":"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/","og_site_name":"Accor MyAllMeeting.com","article_modified_time":"2026-05-13T04:51:48+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/","url":"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/","name":"5944 - ibis Barcelona Plaza Glories 22 - Accor MyAllMeeting.com","isPartOf":{"@id":"https:\/\/www.myallmeeting.com\/en\/#website"},"datePublished":"2020-10-13T10:51:13+00:00","dateModified":"2026-05-13T04:51:48+00:00","breadcrumb":{"@id":"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/myallmeeting.com\/en\/hotel\/5944-ibis-barcelona-pza-glories-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myallmeeting.com\/en\/"},{"@type":"ListItem","position":2,"name":"Hotel","item":"https:\/\/myallmeeting.com\/en\/hotel\/"},{"@type":"ListItem","position":3,"name":"5944 &#8211; ibis Barcelona Plaza Glories 22"}]},{"@type":"WebSite","@id":"https:\/\/www.myallmeeting.com\/en\/#website","url":"https:\/\/www.myallmeeting.com\/en\/","name":"Accor MyAllMeeting.com","description":"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels","publisher":{"@id":"https:\/\/www.myallmeeting.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myallmeeting.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.myallmeeting.com\/en\/#organization","name":"ACCOR","url":"https:\/\/www.myallmeeting.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ACCOR"},"image":{"@id":"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel\/59913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/types\/hotel"}],"wp:attachment":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/media?parent=59913"}],"wp:term":[{"taxonomy":"service","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/service?post=59913"},{"taxonomy":"marque","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/marque?post=59913"},{"taxonomy":"ville","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/ville?post=59913"},{"taxonomy":"partenaire","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/partenaire?post=59913"},{"taxonomy":"type-meeting","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/type-meeting?post=59913"},{"taxonomy":"periscope_activite_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/periscope_activite_tax?post=59913"},{"taxonomy":"periscope_lieu_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/periscope_lieu_tax?post=59913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}