{"id":15979072,"date":"2026-05-13T15:20:39","date_gmt":"2024-07-03T01:15:58","guid":{"rendered":"https:\/\/myallmeeting.com\/hotel\/b1n9-rixos-almaty\/"},"modified":"2026-05-13T17:20:39","modified_gmt":"2026-05-13T15:20:39","slug":"b1n9-rixos-almaty","status":"publish","type":"hotel","link":"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/","title":{"rendered":"B1N9 &#8211; Rixos Almaty"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","service":[591,586,587,588,596,597,600,598,601,605],"marque":[1357],"ville":[9207],"partenaire":[],"type-meeting":[],"periscope_activite_tax":[],"periscope_lieu_tax":[],"class_list":["post-15979072","hotel","type-hotel","status-publish","hentry","service-groom","service-chambres-communicantes","service-concierge-desk","service-connexion-internet-sans-fil-dans-les-espaces-publics","service-parking-pour-bus","service-parking-voiture","service-pools","service-piscine-interieure","service-reception-ouverte-24h-24","service-sauna","marque-rix","ville-almaty"],"acf":[],"yoast_head":"<title>B1N9 - Rixos Almaty - Accor MyAllMeeting.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel\/15979072\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B1N9 - Rixos Almaty - Accor MyAllMeeting.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/\" \/>\n<meta property=\"og:site_name\" content=\"Accor MyAllMeeting.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T15:20:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/\",\"url\":\"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/\",\"name\":\"B1N9 - Rixos Almaty - Accor MyAllMeeting.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#website\"},\"datePublished\":\"2024-07-03T01:15:58+00:00\",\"dateModified\":\"2026-05-13T15:20:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/myallmeeting.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel\",\"item\":\"https:\/\/myallmeeting.com\/en\/hotel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B1N9 &#8211; Rixos Almaty\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#website\",\"url\":\"https:\/\/www.myallmeeting.com\/en\/\",\"name\":\"Accor MyAllMeeting.com\",\"description\":\"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels\",\"publisher\":{\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.myallmeeting.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#organization\",\"name\":\"ACCOR\",\"url\":\"https:\/\/www.myallmeeting.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ACCOR\"},\"image\":{\"@id\":\"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>","yoast_head_json":{"title":"B1N9 - Rixos Almaty - Accor MyAllMeeting.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel\/15979072","og_locale":"en_US","og_type":"article","og_title":"B1N9 - Rixos Almaty - Accor MyAllMeeting.com","og_url":"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/","og_site_name":"Accor MyAllMeeting.com","article_modified_time":"2026-05-13T15:20:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/","url":"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/","name":"B1N9 - Rixos Almaty - Accor MyAllMeeting.com","isPartOf":{"@id":"https:\/\/www.myallmeeting.com\/en\/#website"},"datePublished":"2024-07-03T01:15:58+00:00","dateModified":"2026-05-13T15:20:39+00:00","breadcrumb":{"@id":"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/myallmeeting.com\/en\/hotel\/b1n9-rixos-almaty\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myallmeeting.com\/en\/"},{"@type":"ListItem","position":2,"name":"Hotel","item":"https:\/\/myallmeeting.com\/en\/hotel\/"},{"@type":"ListItem","position":3,"name":"B1N9 &#8211; Rixos Almaty"}]},{"@type":"WebSite","@id":"https:\/\/www.myallmeeting.com\/en\/#website","url":"https:\/\/www.myallmeeting.com\/en\/","name":"Accor MyAllMeeting.com","description":"Les Meilleurs lieux pour vos Ev\u00e9nements Professionnels","publisher":{"@id":"https:\/\/www.myallmeeting.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myallmeeting.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.myallmeeting.com\/en\/#organization","name":"ACCOR","url":"https:\/\/www.myallmeeting.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ACCOR"},"image":{"@id":"https:\/\/www.myallmeeting.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel\/15979072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/types\/hotel"}],"wp:attachment":[{"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/media?parent=15979072"}],"wp:term":[{"taxonomy":"service","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/service?post=15979072"},{"taxonomy":"marque","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/marque?post=15979072"},{"taxonomy":"ville","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/ville?post=15979072"},{"taxonomy":"partenaire","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/partenaire?post=15979072"},{"taxonomy":"type-meeting","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/type-meeting?post=15979072"},{"taxonomy":"periscope_activite_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/periscope_activite_tax?post=15979072"},{"taxonomy":"periscope_lieu_tax","embeddable":true,"href":"https:\/\/myallmeeting.com\/en\/wp-json\/wp\/v2\/periscope_lieu_tax?post=15979072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}